{"id":6102,"date":"2021-04-01T15:03:30","date_gmt":"2021-04-01T14:03:30","guid":{"rendered":"http:\/\/www.liselotte-andersen.net\/?p=6102"},"modified":"2026-02-11T17:13:23","modified_gmt":"2026-02-11T16:13:23","slug":"361-espace-dart-contemporain-aix-en-provence-france","status":"publish","type":"post","link":"https:\/\/www.liselotte-andersen.net\/it\/expositions-ephemeres\/361-espace-dart-contemporain-aix-en-provence-france\/","title":{"rendered":"361\u00b0 \u2013 Espace d\u2019Art Contemporain \u2013 Aix-en-Provence (Francia)"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Une s\u00e9lection de mes anciennes sculptures en terre est pr\u00e9sent\u00e9e dans le cadre du Vide-Atelier organis\u00e9 par la galerie. Profitez encore des 3 jours d&rsquo;ouverture pour venir les d\u00e9couvrir \u00ab\u00a0en r\u00e9el\u00a0\u00bb, \u00e0 partir de dimanche ce sera \u00ab\u00a0en virtuel\u00a0\u00bb compte tenu des nouvelles restrictions sanitaires.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Horaires : de 11h-18h.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adresse : 2 rue de l&rsquo;Annonciade, Aix-en-Provence<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7515-e1769606101693-1024x1024.jpg\" alt=\"\" class=\"wp-image-6105\" style=\"width:546px;height:auto\" srcset=\"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7515-e1769606101693-1024x1024.jpg 1024w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7515-e1769606101693-300x300.jpg 300w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7515-e1769606101693-150x150.jpg 150w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7515-e1769606101693-768x768.jpg 768w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7515-e1769606101693-1536x1536.jpg 1536w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7515-e1769606101693-2048x2048.jpg 2048w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7515-e1769606101693-468x468.jpg 468w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7515-e1769606101693-1612x1612.jpg 1612w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7515-e1769606101693-1116x1116.jpg 1116w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7515-e1769606101693-806x806.jpg 806w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7515-e1769606101693-558x558.jpg 558w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7515-e1769606101693-700x700.jpg 700w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7515-e1769606101693-120x120.jpg 120w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7516-e1769606131721-1024x1024.jpg\" alt=\"\" class=\"wp-image-6107\" style=\"width:547px;height:auto\" srcset=\"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7516-e1769606131721-1024x1024.jpg 1024w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7516-e1769606131721-300x300.jpg 300w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7516-e1769606131721-150x150.jpg 150w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7516-e1769606131721-768x768.jpg 768w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7516-e1769606131721-1536x1536.jpg 1536w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7516-e1769606131721-2048x2048.jpg 2048w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7516-e1769606131721-468x468.jpg 468w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7516-e1769606131721-1612x1612.jpg 1612w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7516-e1769606131721-1116x1116.jpg 1116w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7516-e1769606131721-806x806.jpg 806w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7516-e1769606131721-558x558.jpg 558w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7516-e1769606131721-700x700.jpg 700w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7516-e1769606131721-120x120.jpg 120w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7517-e1769606165634-1024x1024.jpg\" alt=\"\" class=\"wp-image-6109\" style=\"width:546px;height:auto\" srcset=\"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7517-e1769606165634-1024x1024.jpg 1024w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7517-e1769606165634-300x300.jpg 300w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7517-e1769606165634-150x150.jpg 150w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7517-e1769606165634-768x768.jpg 768w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7517-e1769606165634-1536x1536.jpg 1536w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7517-e1769606165634-2048x2048.jpg 2048w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7517-e1769606165634-468x468.jpg 468w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7517-e1769606165634-1612x1612.jpg 1612w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7517-e1769606165634-1116x1116.jpg 1116w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7517-e1769606165634-806x806.jpg 806w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7517-e1769606165634-558x558.jpg 558w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7517-e1769606165634-700x700.jpg 700w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7517-e1769606165634-120x120.jpg 120w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7518-e1769606194340-1024x1024.jpg\" alt=\"\" class=\"wp-image-6111\" style=\"width:547px;height:auto\" srcset=\"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7518-e1769606194340-1024x1024.jpg 1024w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7518-e1769606194340-300x300.jpg 300w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7518-e1769606194340-150x150.jpg 150w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7518-e1769606194340-768x768.jpg 768w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7518-e1769606194340-1536x1536.jpg 1536w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7518-e1769606194340-2048x2048.jpg 2048w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7518-e1769606194340-468x468.jpg 468w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7518-e1769606194340-1612x1612.jpg 1612w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7518-e1769606194340-1116x1116.jpg 1116w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7518-e1769606194340-806x806.jpg 806w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7518-e1769606194340-558x558.jpg 558w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7518-e1769606194340-700x700.jpg 700w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7518-e1769606194340-120x120.jpg 120w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7520-e1769606223138-1024x1024.jpg\" alt=\"\" class=\"wp-image-6113\" style=\"width:548px;height:auto\" srcset=\"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7520-e1769606223138-1024x1024.jpg 1024w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7520-e1769606223138-300x300.jpg 300w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7520-e1769606223138-150x150.jpg 150w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7520-e1769606223138-768x768.jpg 768w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7520-e1769606223138-1536x1536.jpg 1536w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7520-e1769606223138-2048x2048.jpg 2048w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7520-e1769606223138-468x468.jpg 468w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7520-e1769606223138-1612x1612.jpg 1612w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7520-e1769606223138-1116x1116.jpg 1116w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7520-e1769606223138-806x806.jpg 806w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7520-e1769606223138-558x558.jpg 558w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7520-e1769606223138-700x700.jpg 700w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7520-e1769606223138-120x120.jpg 120w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7519-e1769606252142-1024x1024.jpg\" alt=\"\" class=\"wp-image-6115\" style=\"width:549px;height:auto\" srcset=\"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7519-e1769606252142-1024x1024.jpg 1024w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7519-e1769606252142-300x300.jpg 300w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7519-e1769606252142-150x150.jpg 150w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7519-e1769606252142-768x768.jpg 768w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7519-e1769606252142-1536x1536.jpg 1536w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7519-e1769606252142-2048x2048.jpg 2048w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7519-e1769606252142-468x468.jpg 468w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7519-e1769606252142-1612x1612.jpg 1612w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7519-e1769606252142-1116x1116.jpg 1116w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7519-e1769606252142-806x806.jpg 806w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7519-e1769606252142-558x558.jpg 558w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7519-e1769606252142-700x700.jpg 700w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7519-e1769606252142-120x120.jpg 120w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7519-e1769606252142-600x600.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7521-e1769606278684-1024x1024.jpg\" alt=\"\" class=\"wp-image-6117\" style=\"width:551px;height:auto\" srcset=\"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7521-e1769606278684-1024x1024.jpg 1024w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7521-e1769606278684-300x300.jpg 300w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7521-e1769606278684-150x150.jpg 150w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7521-e1769606278684-768x768.jpg 768w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7521-e1769606278684-1536x1536.jpg 1536w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7521-e1769606278684-2048x2048.jpg 2048w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7521-e1769606278684-468x468.jpg 468w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7521-e1769606278684-1612x1612.jpg 1612w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7521-e1769606278684-1116x1116.jpg 1116w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7521-e1769606278684-806x806.jpg 806w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7521-e1769606278684-558x558.jpg 558w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7521-e1769606278684-700x700.jpg 700w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7521-e1769606278684-120x120.jpg 120w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>","protected":false},"excerpt":{"rendered":"<p>Una selezione delle mie vecchie sculture in terracotta \u00e8 presentata nell'ambito del Vide-Atelier organizzato dalla galleria. Approfittate ancora degli ultimi 3 giorni di apertura per venire a scoprirle \u00abdal vivo\u00bb, da domenica saranno \u00abvirtuali\u00bb viste le nuove restrizioni sanitarie. Orari: dalle 11:00 alle 18:00. Indirizzo: 2 rue de l\u2019Annonciade,\u2026<\/p>","protected":false},"author":3,"featured_media":6115,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-6102","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expositions-ephemeres"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>361\u00b0 - Espace d&#039;Art Contemporain - Aix-en-Provence (France) - Liselotte Andersen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.liselotte-andersen.net\/it\/mostre-temporanee\/361-espace-dart-contemporain-aix-en-provence-france\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"361\u00b0 - Espace d&#039;Art Contemporain - Aix-en-Provence (France) - Liselotte Andersen\" \/>\n<meta property=\"og:description\" content=\"Une s\u00e9lection de mes anciennes sculptures en terre est pr\u00e9sent\u00e9e dans le cadre du Vide-Atelier organis\u00e9 par la galerie. Profitez encore des 3 jours d&rsquo;ouverture pour venir les d\u00e9couvrir \u00ab\u00a0en r\u00e9el\u00a0\u00bb, \u00e0 partir de dimanche ce sera \u00ab\u00a0en virtuel\u00a0\u00bb compte tenu des nouvelles restrictions sanitaires. Horaires : de 11h-18h. Adresse : 2 rue de l&rsquo;Annonciade,&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.liselotte-andersen.net\/it\/mostre-temporanee\/361-espace-dart-contemporain-aix-en-provence-france\/\" \/>\n<meta property=\"og:site_name\" content=\"Liselotte Andersen\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-01T14:03:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-11T16:13:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7519-e1769606252142.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2448\" \/>\n\t<meta property=\"og:image:height\" content=\"2448\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Liselotte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Liselotte\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/en\\\/ephemeral-exhibitions\\\/361-espace-dart-contemporain-aix-en-provence-france\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/en\\\/ephemeral-exhibitions\\\/361-espace-dart-contemporain-aix-en-provence-france\\\/\"},\"author\":{\"name\":\"Liselotte\",\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/#\\\/schema\\\/person\\\/e6287e36a81c443bc328eaa434927efc\"},\"headline\":\"361\u00b0 &#8211; Espace d&rsquo;Art Contemporain &#8211; Aix-en-Provence (France)\",\"datePublished\":\"2021-04-01T14:03:30+00:00\",\"dateModified\":\"2026-02-11T16:13:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/en\\\/ephemeral-exhibitions\\\/361-espace-dart-contemporain-aix-en-provence-france\\\/\"},\"wordCount\":67,\"publisher\":{\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/#\\\/schema\\\/person\\\/e6287e36a81c443bc328eaa434927efc\"},\"image\":{\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/en\\\/ephemeral-exhibitions\\\/361-espace-dart-contemporain-aix-en-provence-france\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/IMG_7519-e1769606252142.jpg\",\"articleSection\":[\"Expositions \u00e9ph\u00e9m\u00e8res\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/en\\\/ephemeral-exhibitions\\\/361-espace-dart-contemporain-aix-en-provence-france\\\/\",\"url\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/en\\\/ephemeral-exhibitions\\\/361-espace-dart-contemporain-aix-en-provence-france\\\/\",\"name\":\"361\u00b0 - Espace d'Art Contemporain - Aix-en-Provence (France) - Liselotte Andersen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/en\\\/ephemeral-exhibitions\\\/361-espace-dart-contemporain-aix-en-provence-france\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/en\\\/ephemeral-exhibitions\\\/361-espace-dart-contemporain-aix-en-provence-france\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/IMG_7519-e1769606252142.jpg\",\"datePublished\":\"2021-04-01T14:03:30+00:00\",\"dateModified\":\"2026-02-11T16:13:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/en\\\/ephemeral-exhibitions\\\/361-espace-dart-contemporain-aix-en-provence-france\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.liselotte-andersen.net\\\/en\\\/ephemeral-exhibitions\\\/361-espace-dart-contemporain-aix-en-provence-france\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/en\\\/ephemeral-exhibitions\\\/361-espace-dart-contemporain-aix-en-provence-france\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/IMG_7519-e1769606252142.jpg\",\"contentUrl\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/IMG_7519-e1769606252142.jpg\",\"width\":2448,\"height\":2448},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/en\\\/ephemeral-exhibitions\\\/361-espace-dart-contemporain-aix-en-provence-france\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"361\u00b0 &#8211; Espace d&rsquo;Art Contemporain &#8211; Aix-en-Provence (France)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/#website\",\"url\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/\",\"name\":\"Liselotte Andersen\",\"description\":\"Sculptrice\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/#\\\/schema\\\/person\\\/e6287e36a81c443bc328eaa434927efc\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/#\\\/schema\\\/person\\\/e6287e36a81c443bc328eaa434927efc\",\"name\":\"Liselotte\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-bronze-LA-BR-e1751834958356.png\",\"url\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-bronze-LA-BR-e1751834958356.png\",\"contentUrl\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-bronze-LA-BR-e1751834958356.png\",\"width\":754,\"height\":744,\"caption\":\"Liselotte\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-bronze-LA-BR-e1751834958356.png\"},\"sameAs\":[\"http:\\\/\\\/www.liselotte-andersen.net\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"361\u00b0 - Espace d'Art Contemporain - Aix-en-Provence (France) - Liselotte Andersen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.liselotte-andersen.net\/it\/mostre-temporanee\/361-espace-dart-contemporain-aix-en-provence-france\/","og_locale":"it_IT","og_type":"article","og_title":"361\u00b0 - Espace d'Art Contemporain - Aix-en-Provence (France) - Liselotte Andersen","og_description":"Une s\u00e9lection de mes anciennes sculptures en terre est pr\u00e9sent\u00e9e dans le cadre du Vide-Atelier organis\u00e9 par la galerie. Profitez encore des 3 jours d&rsquo;ouverture pour venir les d\u00e9couvrir \u00ab\u00a0en r\u00e9el\u00a0\u00bb, \u00e0 partir de dimanche ce sera \u00ab\u00a0en virtuel\u00a0\u00bb compte tenu des nouvelles restrictions sanitaires. Horaires : de 11h-18h. Adresse : 2 rue de l&rsquo;Annonciade,&hellip;","og_url":"https:\/\/www.liselotte-andersen.net\/it\/mostre-temporanee\/361-espace-dart-contemporain-aix-en-provence-france\/","og_site_name":"Liselotte Andersen","article_published_time":"2021-04-01T14:03:30+00:00","article_modified_time":"2026-02-11T16:13:23+00:00","og_image":[{"width":2448,"height":2448,"url":"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7519-e1769606252142.jpg","type":"image\/jpeg"}],"author":"Liselotte","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Liselotte"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.liselotte-andersen.net\/en\/ephemeral-exhibitions\/361-espace-dart-contemporain-aix-en-provence-france\/#article","isPartOf":{"@id":"https:\/\/www.liselotte-andersen.net\/en\/ephemeral-exhibitions\/361-espace-dart-contemporain-aix-en-provence-france\/"},"author":{"name":"Liselotte","@id":"https:\/\/www.liselotte-andersen.net\/#\/schema\/person\/e6287e36a81c443bc328eaa434927efc"},"headline":"361\u00b0 &#8211; Espace d&rsquo;Art Contemporain &#8211; Aix-en-Provence (France)","datePublished":"2021-04-01T14:03:30+00:00","dateModified":"2026-02-11T16:13:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.liselotte-andersen.net\/en\/ephemeral-exhibitions\/361-espace-dart-contemporain-aix-en-provence-france\/"},"wordCount":67,"publisher":{"@id":"https:\/\/www.liselotte-andersen.net\/#\/schema\/person\/e6287e36a81c443bc328eaa434927efc"},"image":{"@id":"https:\/\/www.liselotte-andersen.net\/en\/ephemeral-exhibitions\/361-espace-dart-contemporain-aix-en-provence-france\/#primaryimage"},"thumbnailUrl":"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7519-e1769606252142.jpg","articleSection":["Expositions \u00e9ph\u00e9m\u00e8res"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.liselotte-andersen.net\/en\/ephemeral-exhibitions\/361-espace-dart-contemporain-aix-en-provence-france\/","url":"https:\/\/www.liselotte-andersen.net\/en\/ephemeral-exhibitions\/361-espace-dart-contemporain-aix-en-provence-france\/","name":"361\u00b0 - Espace d'Art Contemporain - Aix-en-Provence (France) - Liselotte Andersen","isPartOf":{"@id":"https:\/\/www.liselotte-andersen.net\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.liselotte-andersen.net\/en\/ephemeral-exhibitions\/361-espace-dart-contemporain-aix-en-provence-france\/#primaryimage"},"image":{"@id":"https:\/\/www.liselotte-andersen.net\/en\/ephemeral-exhibitions\/361-espace-dart-contemporain-aix-en-provence-france\/#primaryimage"},"thumbnailUrl":"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7519-e1769606252142.jpg","datePublished":"2021-04-01T14:03:30+00:00","dateModified":"2026-02-11T16:13:23+00:00","breadcrumb":{"@id":"https:\/\/www.liselotte-andersen.net\/en\/ephemeral-exhibitions\/361-espace-dart-contemporain-aix-en-provence-france\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.liselotte-andersen.net\/en\/ephemeral-exhibitions\/361-espace-dart-contemporain-aix-en-provence-france\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.liselotte-andersen.net\/en\/ephemeral-exhibitions\/361-espace-dart-contemporain-aix-en-provence-france\/#primaryimage","url":"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7519-e1769606252142.jpg","contentUrl":"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2021\/04\/IMG_7519-e1769606252142.jpg","width":2448,"height":2448},{"@type":"BreadcrumbList","@id":"https:\/\/www.liselotte-andersen.net\/en\/ephemeral-exhibitions\/361-espace-dart-contemporain-aix-en-provence-france\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.liselotte-andersen.net\/"},{"@type":"ListItem","position":2,"name":"361\u00b0 &#8211; Espace d&rsquo;Art Contemporain &#8211; Aix-en-Provence (France)"}]},{"@type":"WebSite","@id":"https:\/\/www.liselotte-andersen.net\/#website","url":"https:\/\/www.liselotte-andersen.net\/","name":"Liselotte Andersen","description":"Scultrice","publisher":{"@id":"https:\/\/www.liselotte-andersen.net\/#\/schema\/person\/e6287e36a81c443bc328eaa434927efc"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.liselotte-andersen.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Person","Organization"],"@id":"https:\/\/www.liselotte-andersen.net\/#\/schema\/person\/e6287e36a81c443bc328eaa434927efc","name":"Liselotte","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2025\/07\/Logo-bronze-LA-BR-e1751834958356.png","url":"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2025\/07\/Logo-bronze-LA-BR-e1751834958356.png","contentUrl":"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2025\/07\/Logo-bronze-LA-BR-e1751834958356.png","width":754,"height":744,"caption":"Liselotte"},"logo":{"@id":"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2025\/07\/Logo-bronze-LA-BR-e1751834958356.png"},"sameAs":["http:\/\/www.liselotte-andersen.net"]}]}},"_links":{"self":[{"href":"https:\/\/www.liselotte-andersen.net\/it\/wp-json\/wp\/v2\/posts\/6102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.liselotte-andersen.net\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.liselotte-andersen.net\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.liselotte-andersen.net\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.liselotte-andersen.net\/it\/wp-json\/wp\/v2\/comments?post=6102"}],"version-history":[{"count":0,"href":"https:\/\/www.liselotte-andersen.net\/it\/wp-json\/wp\/v2\/posts\/6102\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.liselotte-andersen.net\/it\/wp-json\/wp\/v2\/media\/6115"}],"wp:attachment":[{"href":"https:\/\/www.liselotte-andersen.net\/it\/wp-json\/wp\/v2\/media?parent=6102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.liselotte-andersen.net\/it\/wp-json\/wp\/v2\/categories?post=6102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.liselotte-andersen.net\/it\/wp-json\/wp\/v2\/tags?post=6102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}