{"id":1724,"date":"2019-08-07T14:00:59","date_gmt":"2019-08-07T13:00:59","guid":{"rendered":"http:\/\/liselotte-andersen.net\/?p=1724"},"modified":"2026-01-26T21:31:01","modified_gmt":"2026-01-26T20:31:01","slug":"centre-culturel-de-bonifacio-corse-2019","status":"publish","type":"post","link":"https:\/\/www.liselotte-andersen.net\/it\/expositions-ephemeres\/centre-culturel-de-bonifacio-corse-2019\/","title":{"rendered":"Centre culturel de Bonifacio (Corse) &#8211; 2019"},"content":{"rendered":"<p>Sur invitation de l&rsquo;H\u00f4tel de Ville et du Centre Culturel de Bonifacio, me voici de nouveau en Corse pour 15 jours&#8230;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3655\" src=\"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2020\/11\/Expo-L.-Andersen-pr-web.jpg\" alt=\"\" width=\"600\" height=\"424\" srcset=\"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2020\/11\/Expo-L.-Andersen-pr-web.jpg 600w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2020\/11\/Expo-L.-Andersen-pr-web-300x212.jpg 300w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2020\/11\/Expo-L.-Andersen-pr-web-558x394.jpg 558w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>Sur invitation de l&rsquo;H\u00f4tel de Ville et du Centre Culturel de Bonifacio, me voici de nouveau en Corse pour 15 jours&#8230;<\/p>","protected":false},"author":3,"featured_media":1726,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1724","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-expositions-ephemeres","post_format-post-format-gallery"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Centre culturel de Bonifacio (Corse) - 2019 - Liselotte Andersen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.liselotte-andersen.net\/it\/mostre-temporanee\/centre-culturel-de-bonifacio-corse-2019\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Centre culturel de Bonifacio (Corse) - 2019 - Liselotte Andersen\" \/>\n<meta property=\"og:description\" content=\"Sur invitation de l&rsquo;H\u00f4tel de Ville et du Centre Culturel de Bonifacio, me voici de nouveau en Corse pour 15 jours&#8230;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.liselotte-andersen.net\/it\/mostre-temporanee\/centre-culturel-de-bonifacio-corse-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Liselotte Andersen\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-07T13:00:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-26T20:31:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/08\/Expo-L.-Andersen-pr-web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"424\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Liselotte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Liselotte\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/en\\\/ephemeral-exhibitions\\\/centre-culturel-de-bonifacio-corse-2019\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/en\\\/ephemeral-exhibitions\\\/centre-culturel-de-bonifacio-corse-2019\\\/\"},\"author\":{\"name\":\"Liselotte\",\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/#\\\/schema\\\/person\\\/e6287e36a81c443bc328eaa434927efc\"},\"headline\":\"Centre culturel de Bonifacio (Corse) &#8211; 2019\",\"datePublished\":\"2019-08-07T13:00:59+00:00\",\"dateModified\":\"2026-01-26T20:31:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/en\\\/ephemeral-exhibitions\\\/centre-culturel-de-bonifacio-corse-2019\\\/\"},\"wordCount\":28,\"publisher\":{\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/#\\\/schema\\\/person\\\/e6287e36a81c443bc328eaa434927efc\"},\"image\":{\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/en\\\/ephemeral-exhibitions\\\/centre-culturel-de-bonifacio-corse-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/Expo-L.-Andersen-pr-web.jpg\",\"articleSection\":[\"Expositions \u00e9ph\u00e9m\u00e8res\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/en\\\/ephemeral-exhibitions\\\/centre-culturel-de-bonifacio-corse-2019\\\/\",\"url\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/en\\\/ephemeral-exhibitions\\\/centre-culturel-de-bonifacio-corse-2019\\\/\",\"name\":\"Centre culturel de Bonifacio (Corse) - 2019 - Liselotte Andersen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/en\\\/ephemeral-exhibitions\\\/centre-culturel-de-bonifacio-corse-2019\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/en\\\/ephemeral-exhibitions\\\/centre-culturel-de-bonifacio-corse-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/Expo-L.-Andersen-pr-web.jpg\",\"datePublished\":\"2019-08-07T13:00:59+00:00\",\"dateModified\":\"2026-01-26T20:31:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/en\\\/ephemeral-exhibitions\\\/centre-culturel-de-bonifacio-corse-2019\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.liselotte-andersen.net\\\/en\\\/ephemeral-exhibitions\\\/centre-culturel-de-bonifacio-corse-2019\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/en\\\/ephemeral-exhibitions\\\/centre-culturel-de-bonifacio-corse-2019\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/Expo-L.-Andersen-pr-web.jpg\",\"contentUrl\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/Expo-L.-Andersen-pr-web.jpg\",\"width\":600,\"height\":424},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/en\\\/ephemeral-exhibitions\\\/centre-culturel-de-bonifacio-corse-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Centre culturel de Bonifacio (Corse) &#8211; 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/#website\",\"url\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/\",\"name\":\"Liselotte Andersen\",\"description\":\"Sculptrice\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/#\\\/schema\\\/person\\\/e6287e36a81c443bc328eaa434927efc\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/#\\\/schema\\\/person\\\/e6287e36a81c443bc328eaa434927efc\",\"name\":\"Liselotte\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-bronze-LA-BR-e1751834958356.png\",\"url\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-bronze-LA-BR-e1751834958356.png\",\"contentUrl\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-bronze-LA-BR-e1751834958356.png\",\"width\":754,\"height\":744,\"caption\":\"Liselotte\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-bronze-LA-BR-e1751834958356.png\"},\"sameAs\":[\"http:\\\/\\\/www.liselotte-andersen.net\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Centre culturel de Bonifacio (Corse) - 2019 - Liselotte Andersen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.liselotte-andersen.net\/it\/mostre-temporanee\/centre-culturel-de-bonifacio-corse-2019\/","og_locale":"it_IT","og_type":"article","og_title":"Centre culturel de Bonifacio (Corse) - 2019 - Liselotte Andersen","og_description":"Sur invitation de l&rsquo;H\u00f4tel de Ville et du Centre Culturel de Bonifacio, me voici de nouveau en Corse pour 15 jours&#8230;","og_url":"https:\/\/www.liselotte-andersen.net\/it\/mostre-temporanee\/centre-culturel-de-bonifacio-corse-2019\/","og_site_name":"Liselotte Andersen","article_published_time":"2019-08-07T13:00:59+00:00","article_modified_time":"2026-01-26T20:31:01+00:00","og_image":[{"width":600,"height":424,"url":"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/08\/Expo-L.-Andersen-pr-web.jpg","type":"image\/jpeg"}],"author":"Liselotte","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Liselotte"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.liselotte-andersen.net\/en\/ephemeral-exhibitions\/centre-culturel-de-bonifacio-corse-2019\/#article","isPartOf":{"@id":"https:\/\/www.liselotte-andersen.net\/en\/ephemeral-exhibitions\/centre-culturel-de-bonifacio-corse-2019\/"},"author":{"name":"Liselotte","@id":"https:\/\/www.liselotte-andersen.net\/#\/schema\/person\/e6287e36a81c443bc328eaa434927efc"},"headline":"Centre culturel de Bonifacio (Corse) &#8211; 2019","datePublished":"2019-08-07T13:00:59+00:00","dateModified":"2026-01-26T20:31:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.liselotte-andersen.net\/en\/ephemeral-exhibitions\/centre-culturel-de-bonifacio-corse-2019\/"},"wordCount":28,"publisher":{"@id":"https:\/\/www.liselotte-andersen.net\/#\/schema\/person\/e6287e36a81c443bc328eaa434927efc"},"image":{"@id":"https:\/\/www.liselotte-andersen.net\/en\/ephemeral-exhibitions\/centre-culturel-de-bonifacio-corse-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/08\/Expo-L.-Andersen-pr-web.jpg","articleSection":["Expositions \u00e9ph\u00e9m\u00e8res"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.liselotte-andersen.net\/en\/ephemeral-exhibitions\/centre-culturel-de-bonifacio-corse-2019\/","url":"https:\/\/www.liselotte-andersen.net\/en\/ephemeral-exhibitions\/centre-culturel-de-bonifacio-corse-2019\/","name":"Centre culturel de Bonifacio (Corse) - 2019 - Liselotte Andersen","isPartOf":{"@id":"https:\/\/www.liselotte-andersen.net\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.liselotte-andersen.net\/en\/ephemeral-exhibitions\/centre-culturel-de-bonifacio-corse-2019\/#primaryimage"},"image":{"@id":"https:\/\/www.liselotte-andersen.net\/en\/ephemeral-exhibitions\/centre-culturel-de-bonifacio-corse-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/08\/Expo-L.-Andersen-pr-web.jpg","datePublished":"2019-08-07T13:00:59+00:00","dateModified":"2026-01-26T20:31:01+00:00","breadcrumb":{"@id":"https:\/\/www.liselotte-andersen.net\/en\/ephemeral-exhibitions\/centre-culturel-de-bonifacio-corse-2019\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.liselotte-andersen.net\/en\/ephemeral-exhibitions\/centre-culturel-de-bonifacio-corse-2019\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.liselotte-andersen.net\/en\/ephemeral-exhibitions\/centre-culturel-de-bonifacio-corse-2019\/#primaryimage","url":"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/08\/Expo-L.-Andersen-pr-web.jpg","contentUrl":"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/08\/Expo-L.-Andersen-pr-web.jpg","width":600,"height":424},{"@type":"BreadcrumbList","@id":"https:\/\/www.liselotte-andersen.net\/en\/ephemeral-exhibitions\/centre-culturel-de-bonifacio-corse-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.liselotte-andersen.net\/"},{"@type":"ListItem","position":2,"name":"Centre culturel de Bonifacio (Corse) &#8211; 2019"}]},{"@type":"WebSite","@id":"https:\/\/www.liselotte-andersen.net\/#website","url":"https:\/\/www.liselotte-andersen.net\/","name":"Liselotte Andersen","description":"Scultrice","publisher":{"@id":"https:\/\/www.liselotte-andersen.net\/#\/schema\/person\/e6287e36a81c443bc328eaa434927efc"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.liselotte-andersen.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Person","Organization"],"@id":"https:\/\/www.liselotte-andersen.net\/#\/schema\/person\/e6287e36a81c443bc328eaa434927efc","name":"Liselotte","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2025\/07\/Logo-bronze-LA-BR-e1751834958356.png","url":"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2025\/07\/Logo-bronze-LA-BR-e1751834958356.png","contentUrl":"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2025\/07\/Logo-bronze-LA-BR-e1751834958356.png","width":754,"height":744,"caption":"Liselotte"},"logo":{"@id":"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2025\/07\/Logo-bronze-LA-BR-e1751834958356.png"},"sameAs":["http:\/\/www.liselotte-andersen.net"]}]}},"_links":{"self":[{"href":"https:\/\/www.liselotte-andersen.net\/it\/wp-json\/wp\/v2\/posts\/1724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.liselotte-andersen.net\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.liselotte-andersen.net\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.liselotte-andersen.net\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.liselotte-andersen.net\/it\/wp-json\/wp\/v2\/comments?post=1724"}],"version-history":[{"count":0,"href":"https:\/\/www.liselotte-andersen.net\/it\/wp-json\/wp\/v2\/posts\/1724\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.liselotte-andersen.net\/it\/wp-json\/wp\/v2\/media\/1726"}],"wp:attachment":[{"href":"https:\/\/www.liselotte-andersen.net\/it\/wp-json\/wp\/v2\/media?parent=1724"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.liselotte-andersen.net\/it\/wp-json\/wp\/v2\/categories?post=1724"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.liselotte-andersen.net\/it\/wp-json\/wp\/v2\/tags?post=1724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}