{"id":1687,"date":"2019-06-09T10:11:23","date_gmt":"2019-06-09T09:11:23","guid":{"rendered":"http:\/\/liselotte-andersen.net\/?p=1687"},"modified":"2026-01-26T21:31:01","modified_gmt":"2026-01-26T20:31:01","slug":"consulart-exposition-des-oeuvres-des-consulats-de-marseille-2019","status":"publish","type":"post","link":"https:\/\/www.liselotte-andersen.net\/it\/expositions-ephemeres\/consulart-exposition-des-oeuvres-des-consulats-de-marseille-2019\/","title":{"rendered":"Consul&rsquo;ART &#8211; Exposition des oeuvres des consulats de Marseille &#8211; 2019"},"content":{"rendered":"<p style=\"text-align: left;\">Une exposition organis\u00e9e par la Maison de l&rsquo;Artisanat et des M\u00e9tiers d&rsquo;Art de Marseille.<\/p>\n<p style=\"text-align: left;\">40 artistes s\u00e9lectionn\u00e9s repr\u00e9sentant les consulats de 40 pays.<\/p>\n<p style=\"text-align: left;\">Je repr\u00e9sente le Danemark.<\/p>\n<p style=\"text-align: left;\">C&rsquo;est du 7 juin au 20 juillet 2019.<\/p>\n<p style=\"text-align: left;\">Au plaisir de vous y retrouver !<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1688 aligncenter\" src=\"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-1-e1560071394280.jpg\" alt=\"\" width=\"600\" height=\"857\" srcset=\"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-1-e1560071394280.jpg 600w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-1-e1560071394280-210x300.jpg 210w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-1-e1560071394280-558x797.jpg 558w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>&nbsp;<\/p>\n<div id='gallery-1' class='gallery galleryid-1687 gallery-columns-2 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.liselotte-andersen.net\/it\/consultart-4\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/ConsultArt-4-scaled-1-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/ConsultArt-4-scaled-1-300x225.jpg 300w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/ConsultArt-4-scaled-1-1024x768.jpg 1024w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/ConsultArt-4-scaled-1-768x576.jpg 768w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/ConsultArt-4-scaled-1-1536x1152.jpg 1536w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/ConsultArt-4-scaled-1-2048x1536.jpg 2048w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/ConsultArt-4-scaled-1-1612x1209.jpg 1612w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/ConsultArt-4-scaled-1-1116x837.jpg 1116w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/ConsultArt-4-scaled-1-806x605.jpg 806w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/ConsultArt-4-scaled-1-558x419.jpg 558w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/ConsultArt-4-scaled-1-700x525.jpg 700w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.liselotte-andersen.net\/it\/consulart-3\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-3-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-3-300x300.jpg 300w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-3-1024x1024.jpg 1024w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-3-150x150.jpg 150w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-3-768x768.jpg 768w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-3-468x468.jpg 468w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-3-806x806.jpg 806w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-3-558x558.jpg 558w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-3-700x700.jpg 700w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-3-120x120.jpg 120w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-3.jpg 1080w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.liselotte-andersen.net\/it\/consulart-2-copie\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-2-copie-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-2-copie-300x300.jpg 300w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-2-copie-1024x1024.jpg 1024w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-2-copie-150x150.jpg 150w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-2-copie-768x768.jpg 768w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-2-copie-1536x1536.jpg 1536w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-2-copie-2048x2048.jpg 2048w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-2-copie-468x468.jpg 468w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-2-copie-1612x1612.jpg 1612w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-2-copie-1116x1116.jpg 1116w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-2-copie-806x806.jpg 806w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-2-copie-558x558.jpg 558w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-2-copie-700x700.jpg 700w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-2-copie-120x120.jpg 120w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.liselotte-andersen.net\/it\/consulart-1-copie\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-1-copie-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-1-copie-300x300.jpg 300w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-1-copie-1024x1024.jpg 1024w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-1-copie-150x150.jpg 150w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-1-copie-768x768.jpg 768w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-1-copie-1536x1536.jpg 1536w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-1-copie-2048x2048.jpg 2048w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-1-copie-468x468.jpg 468w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-1-copie-1612x1612.jpg 1612w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-1-copie-1116x1116.jpg 1116w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-1-copie-806x806.jpg 806w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-1-copie-558x558.jpg 558w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-1-copie-700x700.jpg 700w, https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-1-copie-120x120.jpg 120w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Une exposition organis\u00e9e par la Maison de l&rsquo;Artisanat et des M\u00e9tiers d&rsquo;Art de Marseille. 40 artistes s\u00e9lectionn\u00e9s repr\u00e9sentant les consulats de 40 pays. Je repr\u00e9sente le Danemark. C&rsquo;est du 7 juin au 20 juillet 2019. Au plaisir de vous y retrouver ! &nbsp; &nbsp;<\/p>","protected":false},"author":3,"featured_media":1688,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1687","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expositions-ephemeres"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Consul&#039;ART - Exposition des oeuvres des consulats de Marseille - 2019 - Liselotte Andersen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.liselotte-andersen.net\/it\/mostre-temporanee\/consulart-exposition-des-oeuvres-des-consulats-de-marseille-2019\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Consul&#039;ART - Exposition des oeuvres des consulats de Marseille - 2019 - Liselotte Andersen\" \/>\n<meta property=\"og:description\" content=\"Une exposition organis\u00e9e par la Maison de l&rsquo;Artisanat et des M\u00e9tiers d&rsquo;Art de Marseille. 40 artistes s\u00e9lectionn\u00e9s repr\u00e9sentant les consulats de 40 pays. Je repr\u00e9sente le Danemark. C&rsquo;est du 7 juin au 20 juillet 2019. Au plaisir de vous y retrouver ! &nbsp; &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.liselotte-andersen.net\/it\/mostre-temporanee\/consulart-exposition-des-oeuvres-des-consulats-de-marseille-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Liselotte Andersen\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-09T09:11:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-26T20:31:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-1-e1560071394280.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"857\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Liselotte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Liselotte\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/en\\\/ephemeral-exhibitions\\\/consulart-exposition-des-oeuvres-des-consulats-de-marseille-2019\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/en\\\/ephemeral-exhibitions\\\/consulart-exposition-des-oeuvres-des-consulats-de-marseille-2019\\\/\"},\"author\":{\"name\":\"Liselotte\",\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/#\\\/schema\\\/person\\\/e6287e36a81c443bc328eaa434927efc\"},\"headline\":\"Consul&rsquo;ART &#8211; Exposition des oeuvres des consulats de Marseille &#8211; 2019\",\"datePublished\":\"2019-06-09T09:11:23+00:00\",\"dateModified\":\"2026-01-26T20:31:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/en\\\/ephemeral-exhibitions\\\/consulart-exposition-des-oeuvres-des-consulats-de-marseille-2019\\\/\"},\"wordCount\":63,\"publisher\":{\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/#\\\/schema\\\/person\\\/e6287e36a81c443bc328eaa434927efc\"},\"image\":{\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/en\\\/ephemeral-exhibitions\\\/consulart-exposition-des-oeuvres-des-consulats-de-marseille-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Consulart-1-e1560071394280.jpg\",\"articleSection\":[\"Expositions \u00e9ph\u00e9m\u00e8res\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/en\\\/ephemeral-exhibitions\\\/consulart-exposition-des-oeuvres-des-consulats-de-marseille-2019\\\/\",\"url\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/en\\\/ephemeral-exhibitions\\\/consulart-exposition-des-oeuvres-des-consulats-de-marseille-2019\\\/\",\"name\":\"Consul'ART - Exposition des oeuvres des consulats de Marseille - 2019 - Liselotte Andersen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/en\\\/ephemeral-exhibitions\\\/consulart-exposition-des-oeuvres-des-consulats-de-marseille-2019\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/en\\\/ephemeral-exhibitions\\\/consulart-exposition-des-oeuvres-des-consulats-de-marseille-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Consulart-1-e1560071394280.jpg\",\"datePublished\":\"2019-06-09T09:11:23+00:00\",\"dateModified\":\"2026-01-26T20:31:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/en\\\/ephemeral-exhibitions\\\/consulart-exposition-des-oeuvres-des-consulats-de-marseille-2019\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.liselotte-andersen.net\\\/en\\\/ephemeral-exhibitions\\\/consulart-exposition-des-oeuvres-des-consulats-de-marseille-2019\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/en\\\/ephemeral-exhibitions\\\/consulart-exposition-des-oeuvres-des-consulats-de-marseille-2019\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Consulart-1-e1560071394280.jpg\",\"contentUrl\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Consulart-1-e1560071394280.jpg\",\"width\":600,\"height\":857},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/en\\\/ephemeral-exhibitions\\\/consulart-exposition-des-oeuvres-des-consulats-de-marseille-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Consul&rsquo;ART &#8211; Exposition des oeuvres des consulats de Marseille &#8211; 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/#website\",\"url\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/\",\"name\":\"Liselotte Andersen\",\"description\":\"Sculptrice\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/#\\\/schema\\\/person\\\/e6287e36a81c443bc328eaa434927efc\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/#\\\/schema\\\/person\\\/e6287e36a81c443bc328eaa434927efc\",\"name\":\"Liselotte\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-bronze-LA-BR-e1751834958356.png\",\"url\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-bronze-LA-BR-e1751834958356.png\",\"contentUrl\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-bronze-LA-BR-e1751834958356.png\",\"width\":754,\"height\":744,\"caption\":\"Liselotte\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.liselotte-andersen.net\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-bronze-LA-BR-e1751834958356.png\"},\"sameAs\":[\"http:\\\/\\\/www.liselotte-andersen.net\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Consul'ART - Exposition des oeuvres des consulats de Marseille - 2019 - Liselotte Andersen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.liselotte-andersen.net\/it\/mostre-temporanee\/consulart-exposition-des-oeuvres-des-consulats-de-marseille-2019\/","og_locale":"it_IT","og_type":"article","og_title":"Consul'ART - Exposition des oeuvres des consulats de Marseille - 2019 - Liselotte Andersen","og_description":"Une exposition organis\u00e9e par la Maison de l&rsquo;Artisanat et des M\u00e9tiers d&rsquo;Art de Marseille. 40 artistes s\u00e9lectionn\u00e9s repr\u00e9sentant les consulats de 40 pays. Je repr\u00e9sente le Danemark. C&rsquo;est du 7 juin au 20 juillet 2019. Au plaisir de vous y retrouver ! &nbsp; &nbsp;","og_url":"https:\/\/www.liselotte-andersen.net\/it\/mostre-temporanee\/consulart-exposition-des-oeuvres-des-consulats-de-marseille-2019\/","og_site_name":"Liselotte Andersen","article_published_time":"2019-06-09T09:11:23+00:00","article_modified_time":"2026-01-26T20:31:01+00:00","og_image":[{"width":600,"height":857,"url":"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-1-e1560071394280.jpg","type":"image\/jpeg"}],"author":"Liselotte","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Liselotte"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.liselotte-andersen.net\/en\/ephemeral-exhibitions\/consulart-exposition-des-oeuvres-des-consulats-de-marseille-2019\/#article","isPartOf":{"@id":"https:\/\/www.liselotte-andersen.net\/en\/ephemeral-exhibitions\/consulart-exposition-des-oeuvres-des-consulats-de-marseille-2019\/"},"author":{"name":"Liselotte","@id":"https:\/\/www.liselotte-andersen.net\/#\/schema\/person\/e6287e36a81c443bc328eaa434927efc"},"headline":"Consul&rsquo;ART &#8211; Exposition des oeuvres des consulats de Marseille &#8211; 2019","datePublished":"2019-06-09T09:11:23+00:00","dateModified":"2026-01-26T20:31:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.liselotte-andersen.net\/en\/ephemeral-exhibitions\/consulart-exposition-des-oeuvres-des-consulats-de-marseille-2019\/"},"wordCount":63,"publisher":{"@id":"https:\/\/www.liselotte-andersen.net\/#\/schema\/person\/e6287e36a81c443bc328eaa434927efc"},"image":{"@id":"https:\/\/www.liselotte-andersen.net\/en\/ephemeral-exhibitions\/consulart-exposition-des-oeuvres-des-consulats-de-marseille-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-1-e1560071394280.jpg","articleSection":["Expositions \u00e9ph\u00e9m\u00e8res"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.liselotte-andersen.net\/en\/ephemeral-exhibitions\/consulart-exposition-des-oeuvres-des-consulats-de-marseille-2019\/","url":"https:\/\/www.liselotte-andersen.net\/en\/ephemeral-exhibitions\/consulart-exposition-des-oeuvres-des-consulats-de-marseille-2019\/","name":"Consul'ART - Exposition des oeuvres des consulats de Marseille - 2019 - Liselotte Andersen","isPartOf":{"@id":"https:\/\/www.liselotte-andersen.net\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.liselotte-andersen.net\/en\/ephemeral-exhibitions\/consulart-exposition-des-oeuvres-des-consulats-de-marseille-2019\/#primaryimage"},"image":{"@id":"https:\/\/www.liselotte-andersen.net\/en\/ephemeral-exhibitions\/consulart-exposition-des-oeuvres-des-consulats-de-marseille-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-1-e1560071394280.jpg","datePublished":"2019-06-09T09:11:23+00:00","dateModified":"2026-01-26T20:31:01+00:00","breadcrumb":{"@id":"https:\/\/www.liselotte-andersen.net\/en\/ephemeral-exhibitions\/consulart-exposition-des-oeuvres-des-consulats-de-marseille-2019\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.liselotte-andersen.net\/en\/ephemeral-exhibitions\/consulart-exposition-des-oeuvres-des-consulats-de-marseille-2019\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.liselotte-andersen.net\/en\/ephemeral-exhibitions\/consulart-exposition-des-oeuvres-des-consulats-de-marseille-2019\/#primaryimage","url":"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-1-e1560071394280.jpg","contentUrl":"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2019\/06\/Consulart-1-e1560071394280.jpg","width":600,"height":857},{"@type":"BreadcrumbList","@id":"https:\/\/www.liselotte-andersen.net\/en\/ephemeral-exhibitions\/consulart-exposition-des-oeuvres-des-consulats-de-marseille-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.liselotte-andersen.net\/"},{"@type":"ListItem","position":2,"name":"Consul&rsquo;ART &#8211; Exposition des oeuvres des consulats de Marseille &#8211; 2019"}]},{"@type":"WebSite","@id":"https:\/\/www.liselotte-andersen.net\/#website","url":"https:\/\/www.liselotte-andersen.net\/","name":"Liselotte Andersen","description":"Scultrice","publisher":{"@id":"https:\/\/www.liselotte-andersen.net\/#\/schema\/person\/e6287e36a81c443bc328eaa434927efc"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.liselotte-andersen.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Person","Organization"],"@id":"https:\/\/www.liselotte-andersen.net\/#\/schema\/person\/e6287e36a81c443bc328eaa434927efc","name":"Liselotte","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2025\/07\/Logo-bronze-LA-BR-e1751834958356.png","url":"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2025\/07\/Logo-bronze-LA-BR-e1751834958356.png","contentUrl":"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2025\/07\/Logo-bronze-LA-BR-e1751834958356.png","width":754,"height":744,"caption":"Liselotte"},"logo":{"@id":"https:\/\/www.liselotte-andersen.net\/wp-content\/uploads\/2025\/07\/Logo-bronze-LA-BR-e1751834958356.png"},"sameAs":["http:\/\/www.liselotte-andersen.net"]}]}},"_links":{"self":[{"href":"https:\/\/www.liselotte-andersen.net\/it\/wp-json\/wp\/v2\/posts\/1687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.liselotte-andersen.net\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.liselotte-andersen.net\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.liselotte-andersen.net\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.liselotte-andersen.net\/it\/wp-json\/wp\/v2\/comments?post=1687"}],"version-history":[{"count":0,"href":"https:\/\/www.liselotte-andersen.net\/it\/wp-json\/wp\/v2\/posts\/1687\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.liselotte-andersen.net\/it\/wp-json\/wp\/v2\/media\/1688"}],"wp:attachment":[{"href":"https:\/\/www.liselotte-andersen.net\/it\/wp-json\/wp\/v2\/media?parent=1687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.liselotte-andersen.net\/it\/wp-json\/wp\/v2\/categories?post=1687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.liselotte-andersen.net\/it\/wp-json\/wp\/v2\/tags?post=1687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}